{"date":"2018-01-12T10:30:45","title":"Los mitos y verdades de la Formaci\u00f3n Profesional","entradilla":"En Espa\u00f1a la creencia que arraiga en nuestro sistema educativo es priorizar los estudios universitarios, y creer que los estudios de Formaci\u00f3n Profesional son menos importantes. Aqu\u00ed te contamos los mitos y verdades sobre la FP","link":"https:\/\/www.avanzaentucarrera.com\/orientacion\/orientacion-academica\/formacion-profesional\/mitos-verdades-formacion-profesional\/","featured_image_url":"https:\/\/www.avanzaentucarrera.com\/orientacion\/comp\/uploads\/2018\/01\/Mitos-FP.jpg"}