{"date":"2020-01-16T08:13:48","title":"C\u00f3mo convertirte en un profesional de la repoblaci\u00f3n forestal","entradilla":"Si est\u00e1s tratando de decidir tu futuro profesional y tienes vocaci\u00f3n por contribuir a cuidar del planeta, el \u00e1mbito de la repoblaci\u00f3n forestal puede resultarte enormemente satisfactorio. Te contamos c\u00f3mo puedes formarte para convertirte en un experto. \u00a1Sigue leyendo!","link":"https:\/\/www.avanzaentucarrera.com\/orientacion\/orientacion-academica\/formacion-profesional\/repoblacion-forestal\/","featured_image_url":"https:\/\/www.avanzaentucarrera.com\/orientacion\/comp\/uploads\/2019\/12\/AVTC_Repoblacio\u0301n_Forestal.jpg"}