{"date":"2021-04-27T11:30:58","title":"\u00bfEn qu\u00e9 fechas caer\u00e1 la selectividad EvAU 2021?","entradilla":"A estas alturas del curso, todos los estudiantes de Bachillerato est\u00e1n preocupados por las pruebas de la EVaU, el equivalente de la antigua Selectividad. Como en a\u00f1os anteriores, la EVaU 2021 tendr\u00e1 dos fechas de realizaci\u00f3n. La convocatoria ordinaria y la extraordinaria. Ambas ser\u00e1n en verano. Aqu\u00ed encontrar\u00e1s las fechas de ambas organizadas por comunidades y algunos consejos \u00fatiles que te ayudar\u00e1n a afrontar estos ex\u00e1menes.","link":"https:\/\/www.avanzaentucarrera.com\/orientacion\/orientacion-academica\/carreras-grados\/en-que-fechas-caera-la-selectividad-evau-2021\/","featured_image_url":"https:\/\/www.avanzaentucarrera.com\/orientacion\/comp\/uploads\/2021\/04\/AETC_EvAU_2021.jpg"}